{"id":3,"count":2,"description":"","link":"https:\/\/extravagantgrace.razlightprod.com\/fr\/category\/useful\/","name":"Utile","slug":"useful","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/extravagantgrace.razlightprod.com\/fr\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/extravagantgrace.razlightprod.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/extravagantgrace.razlightprod.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/extravagantgrace.razlightprod.com\/fr\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}